{"id":22,"date":"2022-08-29T05:25:50","date_gmt":"2022-08-29T03:25:50","guid":{"rendered":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/"},"modified":"2022-08-30T13:14:56","modified_gmt":"2022-08-30T11:14:56","slug":"woocommerce-ready","status":"publish","type":"page","link":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/","title":{"rendered":"Tienda"},"content":{"rendered":"\n<p>Nos puede encontrar en la siguiente direcci\u00f3n:<\/p>\n\n\n\n<p>Avinguda Cam\u00ed Nou, 7<\/p>\n\n\n\n<p>46910 Benet\u00fasser (Valencia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos puede encontrar en la siguiente direcci\u00f3n: Avinguda Cam\u00ed Nou, 7 46910 Benet\u00fasser (Valencia)<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tienda - Antonio S\u00e1nchez Joyero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tienda - Antonio S\u00e1nchez Joyero\" \/>\n<meta property=\"og:description\" content=\"Nos puede encontrar en la siguiente direcci\u00f3n: Avinguda Cam\u00ed Nou, 7 46910 Benet\u00fasser (Valencia)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/\" \/>\n<meta property=\"og:site_name\" content=\"Antonio S\u00e1nchez Joyero\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T11:14:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/\",\"url\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/\",\"name\":\"Tienda - Antonio S\u00e1nchez Joyero\",\"isPartOf\":{\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#website\"},\"datePublished\":\"2022-08-29T03:25:50+00:00\",\"dateModified\":\"2022-08-30T11:14:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#website\",\"url\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/\",\"name\":\"Antonio S\u00e1nchez Joyero\",\"description\":\"Comercio dedicado a la fabricaci\u00f3n y venta de Joyeria. Contamos con taller de joyeria propio.\",\"publisher\":{\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#organization\",\"name\":\"Antonio S\u00e1nchez Joyero\",\"url\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-content\/uploads\/sites\/2\/2022\/08\/cropped-logo_Antonio_Sanchez-Joyero-e1653368904646-1.jpg\",\"contentUrl\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-content\/uploads\/sites\/2\/2022\/08\/cropped-logo_Antonio_Sanchez-Joyero-e1653368904646-1.jpg\",\"width\":271,\"height\":150,\"caption\":\"Antonio S\u00e1nchez Joyero\"},\"image\":{\"@id\":\"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tienda - Antonio S\u00e1nchez Joyero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/","og_locale":"es_ES","og_type":"article","og_title":"Tienda - Antonio S\u00e1nchez Joyero","og_description":"Nos puede encontrar en la siguiente direcci\u00f3n: Avinguda Cam\u00ed Nou, 7 46910 Benet\u00fasser (Valencia)","og_url":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/","og_site_name":"Antonio S\u00e1nchez Joyero","article_modified_time":"2022-08-30T11:14:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/","url":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/","name":"Tienda - Antonio S\u00e1nchez Joyero","isPartOf":{"@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#website"},"datePublished":"2022-08-29T03:25:50+00:00","dateModified":"2022-08-30T11:14:56+00:00","breadcrumb":{"@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/woocommerce-ready\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/"},{"@type":"ListItem","position":2,"name":"Tienda"}]},{"@type":"WebSite","@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#website","url":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/","name":"Antonio S\u00e1nchez Joyero","description":"Comercio dedicado a la fabricaci\u00f3n y venta de Joyeria. Contamos con taller de joyeria propio.","publisher":{"@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#organization","name":"Antonio S\u00e1nchez Joyero","url":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#\/schema\/logo\/image\/","url":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-content\/uploads\/sites\/2\/2022\/08\/cropped-logo_Antonio_Sanchez-Joyero-e1653368904646-1.jpg","contentUrl":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-content\/uploads\/sites\/2\/2022\/08\/cropped-logo_Antonio_Sanchez-Joyero-e1653368904646-1.jpg","width":271,"height":150,"caption":"Antonio S\u00e1nchez Joyero"},"image":{"@id":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":1,"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/pages\/22\/revisions\/89"}],"wp:attachment":[{"href":"https:\/\/acbenetusser.com\/antoniosanchezjoyero\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}